{"id":6981,"date":"2022-05-13T17:24:56","date_gmt":"2022-05-14T01:24:56","guid":{"rendered":"https:\/\/www.wataxcredit.org\/preguntas-frecuentes\/"},"modified":"2026-08-04T10:27:06","modified_gmt":"2026-08-04T18:27:06","slug":"preguntas-frecuentes","status":"publish","type":"page","link":"https:\/\/www.wataxcredit.org\/es\/preguntas-frecuentes\/","title":{"rendered":"PREGUNTAS FRECUENTES"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Preguntas<\/h2>\n\n\t<script>\n\t\t(function($){\n\t\t\t$(document).ready(function(){\n\t\t\t\tvar schemaFaqSections = $('.schema-faq .schema-faq-section');\n\t\t\t\t$.each( schemaFaqSections, function( index, faqSection ){\n\t\t\t\t\tvar faqSectionId = $(faqSection).attr('id');\n\t\t\t\t\tvar faqSectionQuestion = $(faqSection).find('.schema-faq-question').text().trim();\n\t\t\t\t\tvar faqQuestionPrepareQuestionDOM = '<a href=\"#' + faqSectionId + '\">' + faqSectionQuestion + '<\/a>';\n\t\t\t\t\tif(faqSectionQuestion){\n\t\t\t\t\t\t$('#faq-table-of-links').append(faqQuestionPrepareQuestionDOM);\n\t\t\t\t\t}\n\t\t\t\t} );\n\t\t\t\t$(\"#faq-table-of-links a\").on(\"click\", function () {\n\t\t\t\t\tvar target = $('.wp-block-yoast-faq-block .schema-faq-section').eq($(this).index()); \/\/ Set the target as variable\n\t\t\t\t\t$(\"html, body\").animate(\n\t\t\t\t\t\t{\n\t\t\t\t\t\t\tscrollTop: $(target).offset().top - 130,\n\t\t\t\t\t\t},\n\t\t\t\t\t\t1000\n\t\t\t\t\t);\n\t\t\t\t});\n\t\t\t});\n\t\t})(jQuery);\n\t<\/script>\n\t<style>\n\t\t#faq-table-of-links a{\n\t\t\tdisplay:block;\n\t\t\tmargin:5px 0px;\n\t\t}\n\t<\/style>\n\t<div id=\"faq-table-of-links\"><\/div>\n\t\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">&#8230;<\/p>\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1672332835458\"><strong class=\"schema-faq-question\">\u00bfQu\u00e9 es el Cr\u00e9dito Tributario para Familias Trabajadoras de Washington?<\/strong> <p class=\"schema-faq-answer\">El Cr\u00e9dito Fiscal para Familias Trabajadoras de Washington (WFTC) es un cr\u00e9dito fiscal anual para los residentes de Washington con ingresos bajos o moderados, incluidas las personas indocumentadas y las familias con estatus mixto. <br\/>La cantidad que puedes recibir oscila entre 50 y 1.330 d\u00f3lares, dependiendo del tama\u00f1o de tu familia y de tu nivel de ingresos. <br\/>Puedes comprobar si cumples los requisitos y presentar la solicitud a trav\u00e9s de <a href=\"http:\/\/www.workingfamiliescredit.wa.gov.\/\">la p\u00e1gina web del Cr\u00e9dito Fiscal para Familias Trabajadoras del Departamento de Hacienda del Estado de Washington.<\/a><\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1672332629949\"><strong class=\"schema-faq-question\">\u00bfC\u00f3mo s\u00e9 si soy elegible\/re\u00fano los requisitos?<\/strong> <p class=\"schema-faq-answer\">Para ser elegible, debes <br\/>1. <strong>Haber obtenido al menos 1 $ de ingresos<\/strong> en el a\u00f1o que solicitas.<strong> <\/strong><a href=\"https:\/\/www.irs.gov\/credits-deductions\/individuals\/earned-income-tax-credit\/earned-income-and-earned-income-tax-credit-eitc-tables\"><strong>1. \u00bfQu\u00e9 cuenta como ingresos del trabajo?<\/strong><\/a><br\/>2. <strong>Haber vivido en Washington<\/strong><br\/>Debes haber residido en Washington durante 183 d\u00edas (6 meses) en el a\u00f1o para el que presentas la solicitud. <br\/>3. Tener <strong>entre 25 y 65 a\u00f1os, O tener al menos un hijo que cumpla los requisitos<\/strong><br\/>Las personas sin hijos deben tener entre 25 y 65 a\u00f1os. Si usted tiene hijos que re\u00fanan los requisitos, no hay l\u00edmite en la edad.  <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1672332698685\"><strong class=\"schema-faq-question\">\u00bfQu\u00e9 necesito para solicitarlo?<\/strong> <p class=\"schema-faq-answer\">1. Tus documentos fiscales<br\/>2. Tu n\u00famero de la Seguridad Social o n\u00famero de identificaci\u00f3n individual del contribuyente (ITIN). Si no tiene un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN) vigente o est\u00e1 en proceso de renovarlo, tendr\u00e1 que incluir su solicitud para N\u00famero de Identificaci\u00f3n Personal del Contribuyente del IRS <a href=\"https:\/\/www.irs.gov\/forms-pubs\/about-form-w-7\">(Formulario W-7)<\/a> con su documentaci\u00f3n de los impuestos. <br\/><strong>Opcional:<\/strong><br\/>Tu carn\u00e9 de conducir o documento de identidad expedido por el gobierno estatal o tribal.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1673364352556\"><strong class=\"schema-faq-question\">\u00bfC\u00f3mo puedo solicitar el Cr\u00e9dito Tributario para Familias Trabajadoras?<\/strong> <p class=\"schema-faq-answer\"><strong>Hay varias formas de solicitar el Cr\u00e9dito Fiscal para Familias Trabajadoras:<\/strong><br\/>1. Solic\u00edtalo cuando hagas la declaraci\u00f3n de la renta federal, de forma gratuita en un centro de Asistencia Voluntaria al Contribuyente<br\/>2. Solic\u00edtalo cuando hagas la declaraci\u00f3n de la renta federal, a trav\u00e9s de un preparador fiscal externo (que puede cobrar tasas). 2. Solic\u00edtalo cuando hagas la declaraci\u00f3n de la renta federal, a trav\u00e9s de un preparador de impuestos externo (que puede cobrar tasas)<br\/>3. Solic\u00edtalo despu\u00e9s de hacer la declaraci\u00f3n de la renta utilizando <a href=\"https:\/\/workingfamiliescredit.wa.gov\/\">la solicitud del Departamento de Hacienda<\/a> (en l\u00ednea o en papel). Esto es gratis. <br\/> <br\/><strong>Solic\u00edtalo cuando hagas tus impuestos gratis en un sitio VITA <\/strong><br\/>Si haces tus impuestos gratis en un sitio de Asistencia Voluntaria al Contribuyente, te ayudar\u00e1n a rellenar tu solicitud de Cr\u00e9dito Fiscal para Familias Trabajadoras al mismo tiempo que haces tus impuestos. Consulta una lista de sitios VITA y recursos en nuestra <a href=\"https:\/\/www.wataxcredit.org\/free-tax-prep-resources-in-washington-state\/\">p\u00e1gina Preparaci\u00f3n gratuita de impuestos<\/a>, o llama al 211.   <br\/><br\/><strong>Utilice un servicio externo de preparaci\u00f3n de impuestos.<\/strong><br\/> Algunos programas de preparaci\u00f3n de impuestos de terceros, pero no todos, integran la solicitud del Cr\u00e9dito Tributario para Familias Trabajadoras (WFTC, por sus siglas en ingl\u00e9s). Estos preparadores de impuestos pueden cobrar una tarifa a los solicitantes por completar su solicitud del WFTC, o pueden indicarles que la presenten por su cuenta a trav\u00e9s del Departamento de Ingresos. Puede encontrar <a href=\"https:\/\/workingfamiliescredit.wa.gov\/apply\/apply-using-tax-preparation-software\">una lista de programas de preparaci\u00f3n de impuestos que integran el Cr\u00e9dito Tributario para Familias Trabajadoras<\/a> en el sitio web del Departamento de Ingresos.    <br\/><br\/><strong>Solic\u00edtalo despu\u00e9s de hacer la declaraci\u00f3n de la renta <\/strong><br\/>Si no lo solicitaste a trav\u00e9s de un sitio VITA o de un preparador de impuestos externo, a\u00fan podr\u00e1s hacerlo a trav\u00e9s del Departamento de Hacienda. Esto siempre es gratis. Hay dos formas de solicitarlo:   <br\/><br\/> <strong> Solicitud en l\u00ednea: <\/strong>Puede presentar la solicitud en l\u00ednea, a trav\u00e9s de la p\u00e1gina web del Departamento de Hacienda (Department of Revenue), en ingl\u00e9s o espa\u00f1ol. Para hacerlo, tendr\u00e1 que crear una cuenta de Acceso Seguro Washington (SAW, siglas en ingl\u00e9s) o puede utilizar una cuenta SAW que ya tenga. Esta es la p\u00e1gina web: <a href=\"https:\/\/workingfamiliescredit.wa.gov\/\">https:\/\/workingfamiliescredit.wa.gov\/<\/a>   <br\/><br\/> <strong> Utilice una solicitud en papel: <\/strong>Puede llenar el documento impreso en papel para presentar su solicitud. La <a href=\"https:\/\/workingfamiliescredit.wa.gov\/apply\/apply-paper\">solicitud para ser impresa en papel puede descargarla<\/a> de la p\u00e1gina web del Cr\u00e9dito Tributario para Familias Trabajadoras del Departamento de Hacienda o puede obtenerla en <a href=\"https:\/\/dor.wa.gov\/contact\/local-offices\">una de las oficinas locales.<\/a> La solicitud est\u00e1 disponible en 12 idiomas.  <br\/><\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1673364477506\"><strong class=\"schema-faq-question\">\u00bfCu\u00e1nto dinero recibir\u00e9 y cu\u00e1les son los l\u00edmites de ingresos?<\/strong> <p class=\"schema-faq-answer\">La cantidad que recibir\u00e1s oscila entre 50 y 1.330 d\u00f3lares, dependiendo del n\u00famero de hijos que cumplan los requisitos en tu hogar y de tu nivel de ingresos (mira la tabla de abajo). La cantidad m\u00ednima del cr\u00e9dito es de 50 d\u00f3lares, independientemente del n\u00famero de hijos que tengas que cumplan los requisitos. Los l\u00edmites de ingresos para el WFTC son los mismos que los del Cr\u00e9dito Fiscal por Ingresos del Trabajo federal. Estos l\u00edmites aumentan ligeramente cada a\u00f1o. Puedes consultar los l\u00edmites actuales en la <a href=\"https:\/\/workingfamiliescredit.wa.gov\/eligibility\">p\u00e1gina web<\/a> del Departamento de Hacienda, en la secci\u00f3n \u00ab\u00bfCu\u00e1les son los requisitos de ingresos?\u00bb. Echa un vistazo a la tabla de abajo.       <img loading=\"lazy\" decoding=\"async\" width=\"1088\" height=\"403\" src=\"https:\/\/www.wataxcredit.org\/wp-content\/uploads\/2026\/08\/DOR-WFTC-eligibility-2025.jpg\" class=\"attachment-full size-full\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/www.wataxcredit.org\/wp-content\/uploads\/2026\/08\/DOR-WFTC-eligibility-2025.jpg 1088w, https:\/\/www.wataxcredit.org\/wp-content\/uploads\/2026\/08\/DOR-WFTC-eligibility-2025-300x111.jpg 300w, https:\/\/www.wataxcredit.org\/wp-content\/uploads\/2026\/08\/DOR-WFTC-eligibility-2025-1024x379.jpg 1024w, https:\/\/www.wataxcredit.org\/wp-content\/uploads\/2026\/08\/DOR-WFTC-eligibility-2025-768x284.jpg 768w\" sizes=\"auto, (max-width: 1088px) 100vw, 1088px\" \/><\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674080330702\"><strong class=\"schema-faq-question\"><strong>Si declaro mis impuestos como adulto soltero y sin hijos que re\u00fanan los requisitos, \u00bfsoy elegible?<\/strong><\/strong> <p class=\"schema-faq-answer\">S\u00ed. Si presenta la solicitud como soltero sin hijos, puede optar al Cr\u00e9dito Tributario para Familias Trabajadoras, siempre que usted tenga entre 25 y 65 a\u00f1os de edad.  <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674080346708\"><strong class=\"schema-faq-question\"><strong>\u00bfQui\u00e9nes se consideran como hijos que re\u00fanen los requisitos?<\/strong><\/strong> <p class=\"schema-faq-answer\">Un hijo que re\u00fane los requisitos es un hijo menor de 19 a\u00f1os que vive con usted la mayor parte del a\u00f1o, o un hijo menor de 24 a\u00f1os que est\u00e1 estudiando a tiempo completo al menos durante 5 meses en el a\u00f1o. Tambi\u00e9n cumple los requisitos, un hijo de cualquier edad con una discapacidad de tipo permanente o temporal.  <br\/><br\/>Para ser un hijo computable, tu hijo debe ser tu:<br\/> &#8211; Hijo, hija, hijastro, hijo adoptivo o hijo de acogida<br\/> &#8211; Hermano, hermana, medio hermano, media hermana, hermanastro o hermanastra<br\/> &#8211; Nieto, sobrina o sobrino<br\/><br\/>Su hijo debe tener un N\u00famero de Seguridad Social (tambi\u00e9n conocido como Seguro Social) o N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN) para que usted pueda incluirlo en su declaraci\u00f3n de impuestos. Puede solicitar el N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN) para su hijo, con el Formulario W-7, Solicitud de N\u00famero de Identificaci\u00f3n Personal del Contribuyente del IRS, al momento de presentar su declaraci\u00f3n de impuestos.  <br\/><a href=\"https:\/\/www.irs.gov\/credits-deductions\/individuals\/earned-income-tax-credit\/qualifying-child-rules\" target=\"_blank\" rel=\"noreferrer noopener\">Obtenga m\u00e1s informaci\u00f3n sobre los hijos que re\u00fanen los requisitos<\/a> aqu\u00ed, en la p\u00e1gina web del Servicio de Impuestos Internos (IRS). <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674080432440\"><strong class=\"schema-faq-question\"><strong>\u00bfC\u00f3mo y cu\u00e1ndo recibir\u00e9 mi cr\u00e9dito?<\/strong><\/strong> <p class=\"schema-faq-answer\"><br\/>Para ver el estado de tu cr\u00e9dito, consulta la herramienta &#8220;\u00bfD\u00f3nde est\u00e1 mi reembolso?&#8221; en el<a href=\"https:\/\/workingfamiliescredit.wa.gov\/\"> sitio web del Cr\u00e9dito Fiscal para Familias Trabajadoras del Departamento de Hacienda, <\/a>o llama a su centro de llamadas al 360-763-7300.<br\/><br\/>. Puedes recibir tu cr\u00e9dito en forma de dep\u00f3sito directo, tarjeta de d\u00e9bito prepagada o cheque, que se enviar\u00e1 por correo a la direcci\u00f3n postal que incluyas en tu solicitud.  <br\/><\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674102318162\"><strong class=\"schema-faq-question\"><strong>\u00bfTengo que devolver este dinero o pagar impuestos por ese monto?<\/strong><\/strong> <p class=\"schema-faq-answer\">No. Esto no es un pr\u00e9stamo. No tiene que devolverlo y no pagar\u00e1 impuestos por este dinero.   <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674102341603\"><strong class=\"schema-faq-question\"><strong>\u00bfD\u00f3nde puedo obtener ayuda para completar la solicitud?<\/strong><\/strong> <p class=\"schema-faq-answer\">El Departamento de Hacienda tiene <a href=\"https:\/\/workingfamiliescredit.wa.gov\/resources\/get-help-your-community\" target=\"_blank\" rel=\"noreferrer noopener\">una lista de organizaciones en su sitio web<\/a> que han recibido financiaci\u00f3n para hacer divulgaci\u00f3n y ayudar con las solicitudes.  <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674102487417\"><strong class=\"schema-faq-question\"><strong>\u00bfCu\u00e1nto tiempo debo haber vivido en Washington para tener derecho al Cr\u00e9dito Tributario para Familias Trabajadoras?<\/strong><\/strong> <p class=\"schema-faq-answer\">Debe haber vivido en Washington durante 183 d\u00edas del a\u00f1o fiscal que solicita, para tener derecho al cr\u00e9dito. Ser\u00edan unos seis meses. No necesita haber vivido en Washington todo ese tiempo de manera continua. Por ejemplo, puede haber vivido tres meses, marcharse y volver a vivir tres meses m\u00e1s.  <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674102522541\"><strong class=\"schema-faq-question\"><strong>Hace mucho tiempo que no declaro mis impuestos y es probable que, al solicitar el cr\u00e9dito, tenga deuda por impuestos atrasados. \u00bfTengo que declarar mis impuestos atrasados para recibir el cr\u00e9dito?  <\/strong><\/strong> <p class=\"schema-faq-answer\">S\u00ed, porque tendr\u00e1 que presentar la declaraci\u00f3n de impuestos del a\u00f1o en curso para poder solicitar el Cr\u00e9dito Tributario para Familias Trabajadoras. <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674102554394\"><strong class=\"schema-faq-question\"><strong>\u00bfPuedo solicitar este cr\u00e9dito si tengo una condena anterior en mi historial?<\/strong><\/strong> <p class=\"schema-faq-answer\">S\u00ed. Los antecedentes penales no afectan a tu capacidad para solicitar el Cr\u00e9dito Fiscal para Familias Trabajadoras.   <br\/><\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674102578024\"><strong class=\"schema-faq-question\"><strong>\u00bfInfluir\u00e1 en mis beneficios (como el TANF o el SNAP) si recibo el pago del Cr\u00e9dito Tributario para Familias Trabajadoras? <\/strong><\/strong> <p class=\"schema-faq-answer\">No. Los cr\u00e9ditos tributarios no cuentan como ingresos y no pueden afectar su derecho a beneficios como el TANF o el SNAP.  <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674102613527\"><strong class=\"schema-faq-question\"><strong>\u00bfQu\u00e9 debo hacer si tengo dificultades t\u00e9cnicas o dudas sobre el estado de mi solicitud?<\/strong><\/strong> <p class=\"schema-faq-answer\">Si tiene alguna pregunta que no se responda aqu\u00ed, puede contactar al centro de llamadas del Departamento de Hacienda (Department of Revenue). El n\u00famero telef\u00f3nico es (360) 763-7300. Hay interpretaci\u00f3n disponible.    <br\/><\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674102720019\"><strong class=\"schema-faq-question\"><strong>\u00bfNecesito un N\u00famero de la Seguridad Social (Seguro Social) para solicitar el Cr\u00e9dito Tributario para Familias Trabajadoras?<\/strong><\/strong> <p class=\"schema-faq-answer\">No, no necesita un Seguro Social. Si no tienes n\u00famero de la Seguridad Social, necesitar\u00e1s un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN), que es una alternativa al n\u00famero de la Seguridad Social que s\u00f3lo se utiliza para declarar impuestos, para poder solicitar el Cr\u00e9dito Fiscal para Familias Trabajadoras.   <br\/><\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674233279443\"><strong class=\"schema-faq-question\"><strong>\u00bfQu\u00e9 es un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN)? <\/strong><\/strong> <p class=\"schema-faq-answer\">Un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN) es un n\u00famero para tr\u00e1mites tributarios, emitido por el Servicio de Impuestos Internos (IRS). Las personas que no re\u00fanen los requisitos para obtener un N\u00famero de Seguridad Social pueden utilizar un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN) para presentar su declaraci\u00f3n de impuestos en Estados Unidos. Entre las personas que utilizan un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN) para declarar sus impuestos, est\u00e1n los inmigrantes indocumentados, algunos sobrevivientes de violencia dom\u00e9stica, algunas personas con visa de estudiante y algunos c\u00f3nyuges e hijos de personas con visa de trabajo. Un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN) s\u00f3lo se utiliza para declarar impuestos o abrir una cuenta que pague intereses en Estados Unidos. <a href=\"https:\/\/www.irs.gov\/individuals\/individual-taxpayer-identification-number\" target=\"_blank\" rel=\"noreferrer noopener\">Obtenga m\u00e1s informaci\u00f3n sobre los N\u00fameros de Identificaci\u00f3n del Contribuyente Individual (ITIN) del Servicio de Impuestos Internos (IRS)<\/a>, o visite nuestra <a href=\"https:\/\/www.wataxcredit.org\/es\/recursos-para-solicitantes-de-itin\/\">p\u00e1gina de recursos para personas con N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN).<\/a>     <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674233349847\"><strong class=\"schema-faq-question\"><strong><strong>\u00bfC\u00f3mo puedo solicitar un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN)?<\/strong><\/strong><\/strong> <p class=\"schema-faq-answer\">Visite nuestra <a href=\"https:\/\/www.wataxcredit.org\/es\/recursos-para-solicitantes-de-itin\/\">p\u00e1gina de recursos para solicitantes del <\/a> N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN) y all\u00ed obtendr\u00e1 m\u00e1s informaci\u00f3n sobre c\u00f3mo solicitarlo. <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674233595701\"><strong class=\"schema-faq-question\"><strong>Soy un contribuyente con N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN). \u00bfEs diferente para m\u00ed el proceso de solicitud del Cr\u00e9dito Tributario para Familias Trabajadoras? <\/strong><\/strong> <p class=\"schema-faq-answer\">Si tu ITIN est\u00e1 en vigor y no necesitas solicitarlo o renovarlo, <strong>el proceso de solicitud es exactamente el mismo.<\/strong><br\/>Si necesitas renovar o solicitar un ITIN, tendr\u00e1s que notificar al Departamento de Hacienda del Estado de Washington la renovaci\u00f3n de tu ITIN para recibir el pago del WFTC. <br\/><a href=\"https:\/\/www.irs.gov\/individuals\/itin-expiration-faqs\">M\u00e1s informaci\u00f3n sobre la renovaci\u00f3n del ITIN en el sitio web del IRS.<\/a><br\/><\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674236419760\"><strong class=\"schema-faq-question\"><strong>Tengo un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN), pero mi c\u00f3nyuge no lo tiene, ni tampoco tiene un N\u00famero de Seguridad Social. <\/strong>\u00bfPuedo solicitar el Cr\u00e9dito Tributario para Familias Trabajadoras?<\/strong> <p class=\"schema-faq-answer\">S\u00ed puede solicitarlo. Sin embargo, si va a realizar la presentaci\u00f3n conjunta de declaraci\u00f3n de impuestos, para poder solicitar el Cr\u00e9dito Tributario para Familias Trabajadoras, su c\u00f3nyuge tendr\u00e1 que solicitar un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN) cuando presente la declaraci\u00f3n de impuestos federales. Obtenga m\u00e1s informaci\u00f3n sobre c\u00f3mo solicitar o renovar un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN) <a href=\"https:\/\/www.wataxcredit.org\/es\/recursos-para-solicitantes-de-itin\/\">en nuestra p\u00e1gina de recursos para solicitantes del N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN). <\/a>   <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674236602744\"><strong class=\"schema-faq-question\"><strong>Soy beneficiario de la Acci\u00f3n Diferida para los Llegados en la Infancia (DACA). \u00bfPuedo solicitar el Cr\u00e9dito Tributario para Familias Trabajadoras? <\/strong><\/strong> <p class=\"schema-faq-answer\">Si participa en el beneficio DACA y tiene un N\u00famero de Seguridad Social que le permite trabajar, puede usar ese n\u00famero al solicitar el Cr\u00e9dito Tributario para Familias Trabajadoras.<strong> <\/strong> No necesita solicitar un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN). <\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1674236635782\"><strong class=\"schema-faq-question\"><strong>No estoy seguro de si ya he solicitado el Cr\u00e9dito Fiscal para Familias Trabajadoras. \u00bfC\u00f3mo puedo averiguarlo? <\/strong><\/strong> <p class=\"schema-faq-answer\">Consulta la herramienta <a href=\"https:\/\/workingfamiliescredit.wa.gov\/get-help\/my-dor-help-center\/apply-online-my-dor\/refund\">&#8220;\u00bfD\u00f3nde est\u00e1 mi devoluci\u00f3n?&#8221;<\/a> del Departamento de Hacienda, o llama a su l\u00ednea de ayuda al 360-763-7300. Enviar varias solicitudes puede retrasar tu cr\u00e9dito. <\/p> <\/div> <\/div>\n\n<div class=\"wp-block-group alignfull is-layout-constrained wp-block-group-is-layout-constrained\">\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Preguntas &#8230;<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":["post-6981","page","type-page","status-publish","entry"],"acf":[],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/www.wataxcredit.org\/es\/wp-json\/wp\/v2\/pages\/6981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wataxcredit.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.wataxcredit.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.wataxcredit.org\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wataxcredit.org\/es\/wp-json\/wp\/v2\/comments?post=6981"}],"version-history":[{"count":9,"href":"https:\/\/www.wataxcredit.org\/es\/wp-json\/wp\/v2\/pages\/6981\/revisions"}],"predecessor-version":[{"id":8166,"href":"https:\/\/www.wataxcredit.org\/es\/wp-json\/wp\/v2\/pages\/6981\/revisions\/8166"}],"wp:attachment":[{"href":"https:\/\/www.wataxcredit.org\/es\/wp-json\/wp\/v2\/media?parent=6981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}